{"id":4462,"date":"2019-04-16T10:45:36","date_gmt":"2019-04-16T08:45:36","guid":{"rendered":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux.jpg"},"modified":"2019-04-16T10:46:47","modified_gmt":"2019-04-16T08:46:47","slug":"disco-iluminado-para-evacuacion-camino-iluminado","status":"inherit","type":"attachment","link":"https:\/\/www.cyalume.eu\/es\/chemlight-snaplight-cyalume-glow-stick\/barras-luminosas-y-rotuladores\/marcador-adhesivo-circular-lightshape\/disco-iluminado-para-evacuacion-camino-iluminado\/","title":{"rendered":"disco iluminado para evacuaci\u00f3n camino iluminado"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-4462","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-300x214.jpg\" class=\"attachment-medium size-medium\" alt=\"disque lumineux pour \u00e9vacuation en suivant un cheminement lumineux\" srcset=\"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-300x214.jpg 300w, https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-204x146.jpg 204w, https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-50x36.jpg 50w, https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-105x75.jpg 105w, https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"disque lumineux pour \u00e9vacuation en suivant un cheminement lumineux","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":500,"file":"2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux.jpg","sizes":{"thumbnail":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-150x150.jpg"},"medium":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-300x214.jpg","width":300,"height":214,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-300x214.jpg"},"post-thumbnail":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-204x146.jpg","width":204,"height":146,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-204x146.jpg"},"50x50":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-50x36.jpg","width":50,"height":36,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-50x36.jpg"},"clients-slider":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-105x75.jpg","width":105,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-105x75.jpg"},"testimonials":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-85x85.jpg","width":85,"height":85,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-85x85.jpg"},"blog-navi":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-80x80.jpg"},"portfolio-mf-w":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-700x500.jpg","width":700,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-700x500.jpg"},"blog-single":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux-700x480.jpg","width":700,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux-700x480.jpg"},"full":{"file":"disque-lumineux-pour-evacuation-cheminement-lumineux.jpg","width":700,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":4453,"source_url":"https:\/\/www.cyalume.eu\/wp-content\/uploads\/2019\/04\/disque-lumineux-pour-evacuation-cheminement-lumineux.jpg","_links":{"self":[{"href":"https:\/\/www.cyalume.eu\/es\/wp-json\/wp\/v2\/media\/4462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cyalume.eu\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.cyalume.eu\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.cyalume.eu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cyalume.eu\/es\/wp-json\/wp\/v2\/comments?post=4462"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":4453,"href":"https:\/\/www.cyalume.eu\/es\/wp-json\/wp\/v2\/pages\/4453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}